{"id":149185,"date":"2024-12-11T21:22:38","date_gmt":"2024-12-11T13:22:38","guid":{"rendered":"https:\/\/www.qiyou.cn\/games\/?p=149185"},"modified":"2024-12-11T21:22:39","modified_gmt":"2024-12-11T13:22:39","slug":"%e6%b5%81%e6%94%be%e4%b9%8b%e8%b7%af2%e6%97%a0%e6%b3%95%e8%bf%9e%e6%8e%a5%e8%87%b3%e7%99%bb%e5%bd%95%e6%9c%8d%e5%8a%a1%e5%99%a8%e6%80%8e%e4%b9%88%e5%8a%9e-%e6%b5%81%e6%94%be%e4%b9%8b%e8%b7%af2","status":"publish","type":"post","link":"https:\/\/www.qiyou.cn\/games\/149185.html","title":{"rendered":"\u6d41\u653e\u4e4b\u8def2\u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u600e\u4e48\u529e \u6d41\u653e\u4e4b\u8def2\u767b\u5f55\u95ee\u9898\u89e3\u51b3\u6559\u7a0b"},"content":{"rendered":"\n<p>\u6d41\u653e\u4e4b\u8def2\u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u600e\u4e48\u529e \u6d41\u653e\u4e4b\u8def2\u767b\u5f55\u95ee\u9898\u89e3\u51b3\u6559\u7a0b<\/p>\n\n\n\n<p>\u6d41\u653e\u4e4b\u8def 2 \u4f5c\u4e3a\u4e00\u6b3e\u5907\u53d7\u77a9\u76ee\u7684\u6e38\u620f\uff0c\u4ee5\u5176\u4e30\u5bcc\u7684\u804c\u4e1a\u7cfb\u7edf\u5438\u5f15\u4e86\u4f17\u591a\u73a9\u5bb6\u7684\u76ee\u5149\u3002\u7136\u800c\uff0c\u4e0d\u5c11\u73a9\u5bb6\u5728\u6ee1\u6000\u671f\u5f85\u5730\u767b\u5f55\u6e38\u620f\u65f6\uff0c\u5374\u906d\u9047\u4e86\u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u7684\u56f0\u6270\u3002\u522b\u62c5\u5fc3\uff0c\u9488\u5bf9\u8fd9\u4e00\u95ee\u9898\uff0c\u5c0f\u7f16\u7cbe\u5fc3\u6574\u7406\u4e86\u51e0\u4e2a\u5b9e\u7528\u7684\u89e3\u51b3\u65b9\u6cd5\uff0c\u5927\u5bb6\u53ef\u4ee5\u6839\u636e\u81ea\u8eab\u5b9e\u9645\u60c5\u51b5\u6311\u9009\u5c1d\u8bd5\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4744.png\" alt=\"\" class=\"wp-image-149188\" width=\"817\" height=\"448\" srcset=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4744.png 893w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4744-300x165.png 300w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4744-768x422.png 768w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/><\/figure>\n\n\n\n<p>\u6d41\u653e\u4e4b\u8def2\u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u600e\u4e48\u529e \u6d41\u653e\u4e4b\u8def2\u767b\u5f55\u95ee\u9898\u89e3\u51b3\u6559\u7a0b<\/p>\n\n\n\n<p>\u89e3\u51b3\u65b9\u6cd5\u4e00\uff1a\u4f18\u5316\u7f51\u7edc<\/p>\n\n\n\n<p>\u5728\u5f00\u542f\u6d41\u653e\u4e4b\u8def 2 \u524d\uff0c\u6253\u5f00\u5947\u6e38\u5e76\u641c\u7d22 \u201c\u6d41\u653e\u4e4b\u8def 2\u201d\uff0c\u501f\u52a9\u5947\u6e38\u5f3a\u5927\u7684\u7f51\u7edc\u4f18\u5316\u529f\u80fd\uff0c\u5bf9\u7535\u8111\u672c\u5730\u7f51\u7edc\u73af\u5883\u8fdb\u884c\u6df1\u5ea6\u4f18\u5316\u3002\u5b83\u80fd\u591f\u6709\u6548\u63d0\u5347\u7f51\u7edc\u8fde\u63a5\u7684\u7a33\u5b9a\u6027\u4e0e\u901f\u5ea6\uff0c\u6781\u5927\u53ef\u80fd\u89e3\u51b3\u56e0\u7f51\u7edc\u56e0\u7d20\u5bfc\u81f4\u7684\u767b\u5f55\u95ee\u9898\uff0c\u8ba9\u60a8\u987a\u5229\u8e0f\u5165\u6e38\u620f\u4e16\u754c\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4745-1024x629.png\" alt=\"\" class=\"wp-image-149189\" width=\"817\" height=\"501\" srcset=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4745-1024x629.png 1024w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4745-300x184.png 300w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4745-768x472.png 768w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4745.png 1088w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4746-1024x599.png\" alt=\"\" class=\"wp-image-149190\" width=\"820\" height=\"479\" srcset=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4746-1024x599.png 1024w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4746-300x175.png 300w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4746-768x449.png 768w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4746.png 1076w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n\n<p>\u89e3\u51b3\u65b9\u6cd5\u4e8c\uff1a\u91cd\u542f\u8def\u7531\u5668<\/p>\n\n\n\n<p>\u91cd\u542f\u8def\u7531\u5668\u662f\u4e00\u79cd\u7b80\u5355\u6709\u6548\u7684\u89e3\u51b3\u624b\u6bb5\u3002\u901a\u8fc7\u91cd\u542f\uff0c\u8def\u7531\u5668\u80fd\u591f\u91cd\u65b0\u521d\u59cb\u5316\u7f51\u7edc\u8bbe\u7f6e\uff0c\u6e05\u7406\u7f13\u5b58\u6570\u636e\uff0c\u4e3a\u8bbe\u5907\u4e0e\u6e38\u620f\u670d\u52a1\u5668\u4e4b\u95f4\u7684\u8fde\u63a5\u5efa\u7acb\u4e00\u4e2a\u5168\u65b0\u4e14\u7a33\u5b9a\u7684\u7f51\u7edc\u901a\u9053\uff0c\u6709\u671b\u626b\u9664\u767b\u5f55\u969c\u788d\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4743-1024x463.png\" alt=\"\" class=\"wp-image-149187\" width=\"816\" height=\"368\" srcset=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4743-1024x463.png 1024w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4743-300x136.png 300w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4743-768x347.png 768w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4743.png 1344w\" sizes=\"(max-width: 816px) 100vw, 816px\" \/><\/figure>\n\n\n\n<p>\u89e3\u51b3\u65b9\u6cd5\u4e09\uff1a\u91cd\u7f6e\u7f51\u7edc\u8fde\u63a5<\/p>\n\n\n\n<p>\u91cd\u7f6e\u7f51\u7edc\u8fde\u63a5\u53ef\u5c06\u7f51\u7edc\u53c2\u6570\u6062\u590d\u5230\u521d\u59cb\u72b6\u6001\uff0c\u7ea0\u6b63\u53ef\u80fd\u5b58\u5728\u7684\u9519\u8bef\u914d\u7f6e\u3002\u6b64\u64cd\u4f5c\u80fd\u8ba9\u7cfb\u7edf\u91cd\u65b0\u8bc6\u522b\u7f51\u7edc\u73af\u5883\uff0c\u91cd\u65b0\u5efa\u7acb\u8d77\u7a33\u5b9a\u53ef\u9760\u7684\u7f51\u7edc\u8fde\u63a5\uff0c\u4e3a\u6d41\u653e\u4e4b\u8def 2 \u6210\u529f\u767b\u5f55\u670d\u52a1\u5668\u521b\u9020\u6709\u5229\u6761\u4ef6\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4742.png\" alt=\"\" class=\"wp-image-149186\" width=\"650\" height=\"543\" srcset=\"https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4742.png 414w, https:\/\/www.qiyou.cn\/qy_wordpress\/wp-content\/uploads\/2024\/12\/image-4742-300x251.png 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<p>\u4ee5\u4e0a\u5c31\u662f\u6d41\u653e\u4e4b\u8def 2 \u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u95ee\u9898\u7684\u89e3\u51b3\u529e\u6cd5\u5206\u4eab\uff0c\u5e0c\u671b\u80fd\u591f\u5e2e\u52a9\u5230\u5927\u5bb6\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"\u6d41\u653e\u4e4b\u8def2\u65e0\u6cd5\u8fde\u63a5\u81f3\u767b\u5f55\u670d\u52a1\u5668\u600e\u4e48\u529e \u6d41\u653e\u4e4b\u8def2\u767b\u5f55\u95ee\u9898\u89e3\u51b3\u6559\u7a0b","protected":false},"author":1,"featured_media":149188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/posts\/149185"}],"collection":[{"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/comments?post=149185"}],"version-history":[{"count":1,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/posts\/149185\/revisions"}],"predecessor-version":[{"id":149191,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/posts\/149185\/revisions\/149191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/media\/149188"}],"wp:attachment":[{"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/media?parent=149185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/categories?post=149185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.qiyou.cn\/games\/wp-json\/wp\/v2\/tags?post=149185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}